{"id":6519,"date":"2022-09-05T17:27:02","date_gmt":"2022-09-05T15:27:02","guid":{"rendered":"https:\/\/www.unionjumelages.com\/?p=6519"},"modified":"2022-09-06T10:01:25","modified_gmt":"2022-09-06T08:01:25","slug":"retour-sur-oscar-2022","status":"publish","type":"post","link":"https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/","title":{"rendered":"Retour sur OSCAR 2022"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"6519\" class=\"elementor elementor-6519\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1cdac89 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1cdac89\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-28ef727\" data-id=\"28ef727\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f9a591 elementor-widget elementor-widget-spacer\" data-id=\"2f9a591\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5127332 elementor-widget elementor-widget-heading\" data-id=\"5127332\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Retour sur OSCAR\n du 27 juin au 1er juillet 2022<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-343f82a elementor-widget elementor-widget-template\" data-id=\"343f82a\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e5e4ba8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e5e4ba8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-df48e9d\" data-id=\"df48e9d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cde70fe elementor-widget elementor-widget-image\" data-id=\"cde70fe\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive1-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive1-1024x576.jpg 1024w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive1-300x169.jpg 300w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive1-768x432.jpg 768w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive1.jpg 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cc6be64 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cc6be64\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-79c4fd3\" data-id=\"79c4fd3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36686e2 elementor-widget elementor-widget-image\" data-id=\"36686e2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive2-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive2-1024x576.jpg 1024w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive2-300x169.jpg 300w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive2-768x432.jpg 768w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive2.jpg 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5957330 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5957330\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-150a577\" data-id=\"150a577\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-043b346 elementor-widget elementor-widget-image\" data-id=\"043b346\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive3-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive3-1024x576.jpg 1024w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive3-300x169.jpg 300w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive3-768x432.jpg 768w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive3.jpg 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f1baad elementor-widget elementor-widget-image\" data-id=\"0f1baad\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive4-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive4-1024x576.jpg 1024w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive4-300x169.jpg 300w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive4-768x432.jpg 768w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive4.jpg 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a7feeb9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a7feeb9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-68ba62f\" data-id=\"68ba62f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13bab6b elementor-widget elementor-widget-image\" data-id=\"13bab6b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive5-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive5-1024x576.jpg 1024w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive5-300x169.jpg 300w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive5-768x432.jpg 768w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive5.jpg 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-729eb9d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"729eb9d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8993df0\" data-id=\"8993df0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96b729d elementor-widget elementor-widget-image\" data-id=\"96b729d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive6-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive6-1024x576.jpg 1024w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive6-300x169.jpg 300w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive6-768x432.jpg 768w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive6.jpg 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0048c85 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0048c85\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f524cdb\" data-id=\"f524cdb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d488083 elementor-widget elementor-widget-image\" data-id=\"d488083\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive7-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive7-1024x576.jpg 1024w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive7-300x169.jpg 300w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive7-768x432.jpg 768w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive7.jpg 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1e1cb77 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1e1cb77\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-898bdb1\" data-id=\"898bdb1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a4c547 elementor-widget elementor-widget-image\" data-id=\"9a4c547\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive8-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive8-1024x576.jpg 1024w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive8-300x169.jpg 300w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive8-768x432.jpg 768w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive8.jpg 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a9b2386 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a9b2386\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ebc255e\" data-id=\"ebc255e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a87109 elementor-widget elementor-widget-image\" data-id=\"8a87109\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive9-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive9-1024x576.jpg 1024w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive9-300x169.jpg 300w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive9-768x432.jpg 768w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive9.jpg 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f65169d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f65169d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f14a869\" data-id=\"f14a869\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e24822a elementor-widget elementor-widget-image\" data-id=\"e24822a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive10-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive10-1024x576.jpg 1024w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive10-300x169.jpg 300w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive10-768x432.jpg 768w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive10.jpg 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f0ecbd5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f0ecbd5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-932f15f\" data-id=\"932f15f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1edda87 elementor-widget elementor-widget-image\" data-id=\"1edda87\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive11-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive11-1024x576.jpg 1024w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive11-300x169.jpg 300w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive11-768x432.jpg 768w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive11.jpg 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-38970da elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"38970da\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-43741ba\" data-id=\"43741ba\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eec3a72 elementor-widget elementor-widget-image\" data-id=\"eec3a72\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive12-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive12-1024x576.jpg 1024w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive12-300x169.jpg 300w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive12-768x432.jpg 768w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive12.jpg 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bf2a24d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bf2a24d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4e66531\" data-id=\"4e66531\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a4b326 elementor-widget elementor-widget-image\" data-id=\"3a4b326\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive13-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive13-1024x576.jpg 1024w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive13-300x169.jpg 300w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive13-768x432.jpg 768w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive13.jpg 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bd529c1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bd529c1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ff47a4c\" data-id=\"ff47a4c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40633e3 elementor-widget elementor-widget-image\" data-id=\"40633e3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive14-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive14-1024x576.jpg 1024w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive14-300x169.jpg 300w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive14-768x432.jpg 768w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive14.jpg 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-348a949 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"348a949\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5807843\" data-id=\"5807843\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e037f0a elementor-widget elementor-widget-image\" data-id=\"e037f0a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive15-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive15-1024x576.jpg 1024w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive15-300x169.jpg 300w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive15-768x432.jpg 768w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive15.jpg 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb1e700 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"cb1e700\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"mailto:sylvie.henrypruvot@orange.fr\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactez Lille<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Re-vivez l&#8217;immense succ\u00e8s d&#8217;Oscar 2022 organis\u00e9 par Lille<\/p>\n","protected":false},"author":1,"featured_media":6567,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-6519","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vie-associative"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Retour sur OSCAR 2022 - Union Jumelages<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retour sur OSCAR 2022 - Union Jumelages\" \/>\n<meta property=\"og:description\" content=\"Re-vivez l&#039;immense succ\u00e8s d&#039;Oscar 2022 organis\u00e9 par Lille\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Union Jumelages\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-05T15:27:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-06T08:01:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive16.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"848\" \/>\n\t<meta property=\"og:image:height\" content=\"673\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\/\/www.unionjumelages.com\/#\/schema\/person\/30d99fce985b1ea8051e9a761aff8f70\"},\"headline\":\"Retour sur OSCAR 2022\",\"datePublished\":\"2022-09-05T15:27:02+00:00\",\"dateModified\":\"2022-09-06T08:01:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/\"},\"wordCount\":13,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.unionjumelages.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive16.jpg\",\"articleSection\":[\"Vie associative\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/\",\"url\":\"https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/\",\"name\":\"Retour sur OSCAR 2022 - Union Jumelages\",\"isPartOf\":{\"@id\":\"https:\/\/www.unionjumelages.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive16.jpg\",\"datePublished\":\"2022-09-05T15:27:02+00:00\",\"dateModified\":\"2022-09-06T08:01:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/#primaryimage\",\"url\":\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive16.jpg\",\"contentUrl\":\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive16.jpg\",\"width\":848,\"height\":673},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.unionjumelages.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retour sur OSCAR 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.unionjumelages.com\/#website\",\"url\":\"https:\/\/www.unionjumelages.com\/\",\"name\":\"Union Jumelages\",\"description\":\"Un site utilisant WordPress\",\"publisher\":{\"@id\":\"https:\/\/www.unionjumelages.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.unionjumelages.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.unionjumelages.com\/#organization\",\"name\":\"Union Jumelages\",\"url\":\"https:\/\/www.unionjumelages.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.unionjumelages.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2021\/03\/cropped-union-jumelages.jpg\",\"contentUrl\":\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2021\/03\/cropped-union-jumelages.jpg\",\"width\":113,\"height\":95,\"caption\":\"Union Jumelages\"},\"image\":{\"@id\":\"https:\/\/www.unionjumelages.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.unionjumelages.com\/#\/schema\/person\/30d99fce985b1ea8051e9a761aff8f70\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.unionjumelages.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/30cfcdafa1380b7e07a91661c4a92d2c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/30cfcdafa1380b7e07a91661c4a92d2c?s=96&d=mm&r=g\",\"caption\":\"Admin\"},\"sameAs\":[\"https:\/\/www.unionjumelages.com\"],\"url\":\"https:\/\/www.unionjumelages.com\/index.php\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Retour sur OSCAR 2022 - Union Jumelages","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/","og_locale":"en_US","og_type":"article","og_title":"Retour sur OSCAR 2022 - Union Jumelages","og_description":"Re-vivez l'immense succ\u00e8s d'Oscar 2022 organis\u00e9 par Lille","og_url":"https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/","og_site_name":"Union Jumelages","article_published_time":"2022-09-05T15:27:02+00:00","article_modified_time":"2022-09-06T08:01:25+00:00","og_image":[{"width":848,"height":673,"url":"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive16.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Admin","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/#article","isPartOf":{"@id":"https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/"},"author":{"name":"Admin","@id":"https:\/\/www.unionjumelages.com\/#\/schema\/person\/30d99fce985b1ea8051e9a761aff8f70"},"headline":"Retour sur OSCAR 2022","datePublished":"2022-09-05T15:27:02+00:00","dateModified":"2022-09-06T08:01:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/"},"wordCount":13,"commentCount":0,"publisher":{"@id":"https:\/\/www.unionjumelages.com\/#organization"},"image":{"@id":"https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive16.jpg","articleSection":["Vie associative"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/","url":"https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/","name":"Retour sur OSCAR 2022 - Union Jumelages","isPartOf":{"@id":"https:\/\/www.unionjumelages.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/#primaryimage"},"image":{"@id":"https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive16.jpg","datePublished":"2022-09-05T15:27:02+00:00","dateModified":"2022-09-06T08:01:25+00:00","breadcrumb":{"@id":"https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/#primaryimage","url":"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive16.jpg","contentUrl":"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2022\/07\/Diapositive16.jpg","width":848,"height":673},{"@type":"BreadcrumbList","@id":"https:\/\/www.unionjumelages.com\/index.php\/2022\/09\/05\/retour-sur-oscar-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.unionjumelages.com\/"},{"@type":"ListItem","position":2,"name":"Retour sur OSCAR 2022"}]},{"@type":"WebSite","@id":"https:\/\/www.unionjumelages.com\/#website","url":"https:\/\/www.unionjumelages.com\/","name":"Union Jumelages","description":"Un site utilisant WordPress","publisher":{"@id":"https:\/\/www.unionjumelages.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unionjumelages.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.unionjumelages.com\/#organization","name":"Union Jumelages","url":"https:\/\/www.unionjumelages.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.unionjumelages.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2021\/03\/cropped-union-jumelages.jpg","contentUrl":"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2021\/03\/cropped-union-jumelages.jpg","width":113,"height":95,"caption":"Union Jumelages"},"image":{"@id":"https:\/\/www.unionjumelages.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.unionjumelages.com\/#\/schema\/person\/30d99fce985b1ea8051e9a761aff8f70","name":"Admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.unionjumelages.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/30cfcdafa1380b7e07a91661c4a92d2c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/30cfcdafa1380b7e07a91661c4a92d2c?s=96&d=mm&r=g","caption":"Admin"},"sameAs":["https:\/\/www.unionjumelages.com"],"url":"https:\/\/www.unionjumelages.com\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.unionjumelages.com\/index.php\/wp-json\/wp\/v2\/posts\/6519"}],"collection":[{"href":"https:\/\/www.unionjumelages.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unionjumelages.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unionjumelages.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unionjumelages.com\/index.php\/wp-json\/wp\/v2\/comments?post=6519"}],"version-history":[{"count":20,"href":"https:\/\/www.unionjumelages.com\/index.php\/wp-json\/wp\/v2\/posts\/6519\/revisions"}],"predecessor-version":[{"id":6579,"href":"https:\/\/www.unionjumelages.com\/index.php\/wp-json\/wp\/v2\/posts\/6519\/revisions\/6579"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unionjumelages.com\/index.php\/wp-json\/wp\/v2\/media\/6567"}],"wp:attachment":[{"href":"https:\/\/www.unionjumelages.com\/index.php\/wp-json\/wp\/v2\/media?parent=6519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unionjumelages.com\/index.php\/wp-json\/wp\/v2\/categories?post=6519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unionjumelages.com\/index.php\/wp-json\/wp\/v2\/tags?post=6519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}