{"id":1721,"date":"2021-03-29T11:04:20","date_gmt":"2021-03-29T09:04:20","guid":{"rendered":"https:\/\/www.unionjumelages.com\/?p=1721"},"modified":"2021-04-09T11:20:42","modified_gmt":"2021-04-09T09:20:42","slug":"etre-jumeleur-temoignage-de-lassociation-de-valence","status":"publish","type":"post","link":"https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/","title":{"rendered":"\u00catre &#8220;jumeleur&#8221;"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1721\" class=\"elementor elementor-1721\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ff617c1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ff617c1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2ac9f5d\" data-id=\"2ac9f5d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-266a617 elementor-widget elementor-widget-spacer\" data-id=\"266a617\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29f7b4e elementor-widget elementor-widget-spacer\" data-id=\"29f7b4e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e3482de elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e3482de\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-02dbf46\" data-id=\"02dbf46\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e3c194d elementor-widget elementor-widget-heading\" data-id=\"e3c194d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00catre \"jumeleur\", t\u00e9moignage de l'association de Valence...<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-589275c elementor-widget elementor-widget-spacer\" data-id=\"589275c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-04126f3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"04126f3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c9a0997\" data-id=\"c9a0997\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2fa5778 elementor-widget elementor-widget-spacer\" data-id=\"2fa5778\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb08f72 elementor-widget elementor-widget-spacer\" data-id=\"eb08f72\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9ce81a elementor-widget elementor-widget-image\" data-id=\"d9ce81a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2021\/03\/BIBERACH-K1FR9669--1024x682.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2021\/03\/BIBERACH-K1FR9669--1024x682.jpg 1024w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2021\/03\/BIBERACH-K1FR9669--300x200.jpg 300w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2021\/03\/BIBERACH-K1FR9669--768x511.jpg 768w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2021\/03\/BIBERACH-K1FR9669--1536x1022.jpg 1536w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2021\/03\/BIBERACH-K1FR9669-.jpg 1803w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-969d002 elementor-widget elementor-widget-text-editor\" data-id=\"969d002\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Petit jeu :<br \/>Qui sont les Allemands ? Qui sont les Fran\u00e7ais ?<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-e221cf4\" data-id=\"e221cf4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1843d6 elementor-widget elementor-widget-text-editor\" data-id=\"f1843d6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>T\u00e9moignages de jumeleurs de l\u2019Association des Postiers et T\u00e9l\u00e9communiquants de Valence<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &#8211; Claudie, Jacqueline, Guy et Fran\u00e7oise, Martine, Fred et Daniel:<\/p>\n<p>1- Le jumelage est pour moi un \u00e9change de tous les jours (t\u00e9l\u00e9phone, mail, courrier) avec des amis qui sont aujourd&#8217;hui des membres de notre famille. Apr\u00e8s 36 ans de jumelage (pour ce qui me concerne), c&#8217;est un peu normal&#8230;<br>2- Mots cl\u00e9 : amiti\u00e9, \u00e9change, joie, f\u00eate, convivialit\u00e9, participation, partage des joies et des peines. Tisser des liens. Echanges culturels, faire vivre l\u2019Europe. Respect entre tous.<br>3- Anecdotes : elles sont bien trop nombreuses pour les r\u00e9sumer. Ceci n&#8217;en est pas une, mais on peut en parler : nous sommes aujourd&#8217;hui \u00e0 la troisi\u00e8me g\u00e9n\u00e9ration de jumeleurs: apr\u00e8s nos enfants, ce sont maintenant nos petits-enfants qui nous accompagnent.Nous avons assist\u00e9 \u00e0 des mariages, des naissances, des d\u00e9c\u00e8s&#8230; Nous suivons les \u00e9tudes de nos &#8220;jeunes&#8221;, et quand ils r\u00e9ussissent, c&#8217;est toujours une joie, quand ils trouvent du travail aussi&#8230; Aujourd&#8217;hui nos petits-enfants respectifs apprennent le fran\u00e7ais pour les petits allemands, et l&#8217;allemand pour les petits fran\u00e7ais&#8230; Bel espoir, non ?<br>Lors de la derni\u00e8re r\u00e9ception, nous avons \u00abr\u00e9ussi\u00bb \u00e0 leur faire d\u00e9guster des grenouilles en Ard\u00e8che : moment inoubliable.<br>4- Nous devons poursuivre au maximum ces \u00e9changes qui, bien modestement, luttent contre les extr\u00e9mismes qui s&#8217;installent peu \u00e0 peu en Europe. Ce sont des \u00e9changes de citoyens. Ils nous confortent dans notre sentiment d&#8217;appartenir \u00e0 une unit\u00e9, l&#8217;unit\u00e9 europ\u00e9enne, et nous aident \u00e0 nous sentir europ\u00e9ens : ce n&#8217;est pas uniquement une id\u00e9e, c&#8217;est une r\u00e9alit\u00e9.<br>Connaitre d\u2019autres personnes avec des cultures et des mani\u00e8res de vivre diff\u00e9rents. C\u2019est la tol\u00e9rance.<br>5- COVID = isolement. Nous avons eu trois d\u00e9c\u00e8s dans notre groupe en Allemagne cette ann\u00e9e, et pas de visite possible pour assurer notre soutien \u00e0 ceux qui restent. Il a fallu reprendre la plume (r\u00e9elle ou \u00e9lectronique). Ce n&#8217;est pas pareil. Cette semaine, j&#8217;ai eu un appel t\u00e9l\u00e9phonique de ma jumeleuse pour me souhaiter mon anniversaire, et pour confirmer que nous sommes attendus chez eux d\u00e8s que l&#8217;\u00e9pid\u00e9mie le permettra. Elle m&#8217;assurait aussi qu&#8217;elle esp\u00e9rait que notre petit-fils nous accompagnerait&#8230; Que dire de plus ??????<\/p>\n<p>Fran\u00e7ois FOURCADE Pr\u00e9sident.<\/p>\n<p>06.09.87.09.10<\/p>\n<p>francois.fourcade702@orange.fr<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e2207b elementor-widget elementor-widget-button\" data-id=\"4e2207b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"mailto:francois.fourcade702@orange.fr\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactez-nous \u00e0 Valence<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez le t\u00e9moignage de l&#8217;association de Valence !<\/p>\n","protected":false},"author":1,"featured_media":1836,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1721","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vie-associative"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00catre &quot;jumeleur&quot; - Union Jumelages<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00catre &quot;jumeleur&quot; - Union Jumelages\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez le t\u00e9moignage de l&#039;association de Valence !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/\" \/>\n<meta property=\"og:site_name\" content=\"Union Jumelages\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-29T09:04:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-09T09:20:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2021\/03\/GROTTE-CHAUVET-IMGP6196-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1701\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\/\/www.unionjumelages.com\/#\/schema\/person\/30d99fce985b1ea8051e9a761aff8f70\"},\"headline\":\"\u00catre &#8220;jumeleur&#8221;\",\"datePublished\":\"2021-03-29T09:04:20+00:00\",\"dateModified\":\"2021-04-09T09:20:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/\"},\"wordCount\":439,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.unionjumelages.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2021\/03\/GROTTE-CHAUVET-IMGP6196-scaled.jpg\",\"articleSection\":[\"Vie associative\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/\",\"url\":\"https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/\",\"name\":\"\u00catre \\\"jumeleur\\\" - Union Jumelages\",\"isPartOf\":{\"@id\":\"https:\/\/www.unionjumelages.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2021\/03\/GROTTE-CHAUVET-IMGP6196-scaled.jpg\",\"datePublished\":\"2021-03-29T09:04:20+00:00\",\"dateModified\":\"2021-04-09T09:20:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/#primaryimage\",\"url\":\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2021\/03\/GROTTE-CHAUVET-IMGP6196-scaled.jpg\",\"contentUrl\":\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2021\/03\/GROTTE-CHAUVET-IMGP6196-scaled.jpg\",\"width\":2560,\"height\":1701},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.unionjumelages.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00catre &#8220;jumeleur&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.unionjumelages.com\/#website\",\"url\":\"https:\/\/www.unionjumelages.com\/\",\"name\":\"Union Jumelages\",\"description\":\"Un site utilisant WordPress\",\"publisher\":{\"@id\":\"https:\/\/www.unionjumelages.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.unionjumelages.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.unionjumelages.com\/#organization\",\"name\":\"Union Jumelages\",\"url\":\"https:\/\/www.unionjumelages.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.unionjumelages.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2021\/03\/cropped-union-jumelages.jpg\",\"contentUrl\":\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2021\/03\/cropped-union-jumelages.jpg\",\"width\":113,\"height\":95,\"caption\":\"Union Jumelages\"},\"image\":{\"@id\":\"https:\/\/www.unionjumelages.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.unionjumelages.com\/#\/schema\/person\/30d99fce985b1ea8051e9a761aff8f70\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.unionjumelages.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/30cfcdafa1380b7e07a91661c4a92d2c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/30cfcdafa1380b7e07a91661c4a92d2c?s=96&d=mm&r=g\",\"caption\":\"Admin\"},\"sameAs\":[\"https:\/\/www.unionjumelages.com\"],\"url\":\"https:\/\/www.unionjumelages.com\/index.php\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00catre \"jumeleur\" - Union Jumelages","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/","og_locale":"en_US","og_type":"article","og_title":"\u00catre \"jumeleur\" - Union Jumelages","og_description":"D\u00e9couvrez le t\u00e9moignage de l'association de Valence !","og_url":"https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/","og_site_name":"Union Jumelages","article_published_time":"2021-03-29T09:04:20+00:00","article_modified_time":"2021-04-09T09:20:42+00:00","og_image":[{"width":2560,"height":1701,"url":"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2021\/03\/GROTTE-CHAUVET-IMGP6196-scaled.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Admin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/#article","isPartOf":{"@id":"https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/"},"author":{"name":"Admin","@id":"https:\/\/www.unionjumelages.com\/#\/schema\/person\/30d99fce985b1ea8051e9a761aff8f70"},"headline":"\u00catre &#8220;jumeleur&#8221;","datePublished":"2021-03-29T09:04:20+00:00","dateModified":"2021-04-09T09:20:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/"},"wordCount":439,"commentCount":0,"publisher":{"@id":"https:\/\/www.unionjumelages.com\/#organization"},"image":{"@id":"https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2021\/03\/GROTTE-CHAUVET-IMGP6196-scaled.jpg","articleSection":["Vie associative"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/","url":"https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/","name":"\u00catre \"jumeleur\" - Union Jumelages","isPartOf":{"@id":"https:\/\/www.unionjumelages.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/#primaryimage"},"image":{"@id":"https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2021\/03\/GROTTE-CHAUVET-IMGP6196-scaled.jpg","datePublished":"2021-03-29T09:04:20+00:00","dateModified":"2021-04-09T09:20:42+00:00","breadcrumb":{"@id":"https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/#primaryimage","url":"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2021\/03\/GROTTE-CHAUVET-IMGP6196-scaled.jpg","contentUrl":"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2021\/03\/GROTTE-CHAUVET-IMGP6196-scaled.jpg","width":2560,"height":1701},{"@type":"BreadcrumbList","@id":"https:\/\/www.unionjumelages.com\/index.php\/2021\/03\/29\/etre-jumeleur-temoignage-de-lassociation-de-valence\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.unionjumelages.com\/"},{"@type":"ListItem","position":2,"name":"\u00catre &#8220;jumeleur&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.unionjumelages.com\/#website","url":"https:\/\/www.unionjumelages.com\/","name":"Union Jumelages","description":"Un site utilisant WordPress","publisher":{"@id":"https:\/\/www.unionjumelages.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unionjumelages.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.unionjumelages.com\/#organization","name":"Union Jumelages","url":"https:\/\/www.unionjumelages.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.unionjumelages.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2021\/03\/cropped-union-jumelages.jpg","contentUrl":"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2021\/03\/cropped-union-jumelages.jpg","width":113,"height":95,"caption":"Union Jumelages"},"image":{"@id":"https:\/\/www.unionjumelages.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.unionjumelages.com\/#\/schema\/person\/30d99fce985b1ea8051e9a761aff8f70","name":"Admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.unionjumelages.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/30cfcdafa1380b7e07a91661c4a92d2c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/30cfcdafa1380b7e07a91661c4a92d2c?s=96&d=mm&r=g","caption":"Admin"},"sameAs":["https:\/\/www.unionjumelages.com"],"url":"https:\/\/www.unionjumelages.com\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.unionjumelages.com\/index.php\/wp-json\/wp\/v2\/posts\/1721"}],"collection":[{"href":"https:\/\/www.unionjumelages.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unionjumelages.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unionjumelages.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unionjumelages.com\/index.php\/wp-json\/wp\/v2\/comments?post=1721"}],"version-history":[{"count":38,"href":"https:\/\/www.unionjumelages.com\/index.php\/wp-json\/wp\/v2\/posts\/1721\/revisions"}],"predecessor-version":[{"id":2302,"href":"https:\/\/www.unionjumelages.com\/index.php\/wp-json\/wp\/v2\/posts\/1721\/revisions\/2302"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unionjumelages.com\/index.php\/wp-json\/wp\/v2\/media\/1836"}],"wp:attachment":[{"href":"https:\/\/www.unionjumelages.com\/index.php\/wp-json\/wp\/v2\/media?parent=1721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unionjumelages.com\/index.php\/wp-json\/wp\/v2\/categories?post=1721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unionjumelages.com\/index.php\/wp-json\/wp\/v2\/tags?post=1721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}