{"id":300,"date":"2021-03-17T10:13:08","date_gmt":"2021-03-17T09:13:08","guid":{"rendered":"https:\/\/www.unionjumelages.com\/?page_id=300"},"modified":"2022-06-30T21:15:24","modified_gmt":"2022-06-30T19:15:24","slug":"vie-associative","status":"publish","type":"page","link":"https:\/\/www.unionjumelages.com\/index.php\/vie-associative\/","title":{"rendered":"Vie associative"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"300\" class=\"elementor elementor-300\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1cd64c9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1cd64c9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1688112\" data-id=\"1688112\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-807d29a elementor-widget elementor-widget-heading\" data-id=\"807d29a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vie associative<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-98e3ac3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"98e3ac3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2e87b14\" data-id=\"2e87b14\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f98e9fe elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-card-shadow-yes elementor-posts__hover-gradient elementor-widget elementor-widget-posts\" data-id=\"f98e9fe\" data-element_type=\"widget\" data-settings=\"{&quot;cards_columns&quot;:&quot;3&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-13665 post type-post status-publish format-standard has-post-thumbnail hentry category-activites category-culture-et-langues category-vie-associative\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2026\/04\/20\/nouveau-sejours-linguistiques-jeunes\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/04\/IMG_20250816_182158-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/04\/IMG_20250816_182158-300x225.jpg 300w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/04\/IMG_20250816_182158-1024x768.jpg 1024w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/04\/IMG_20250816_182158-768x576.jpg 768w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/04\/IMG_20250816_182158-1536x1152.jpg 1536w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/04\/IMG_20250816_182158-2048x1536.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Activit\u00e9s<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.unionjumelages.com\/index.php\/2026\/04\/20\/nouveau-sejours-linguistiques-jeunes\/\" >\n\t\t\t\tS\u00e9jours linguistiques jeunes en Angleterre et ailleurs\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Vacances scolaires 2026 Nouveaux discounts avec l&#8217;UNJPT<\/p>\n\t\t<\/div>\n\t\t\t\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2026\/04\/20\/nouveau-sejours-linguistiques-jeunes\/\" >\n\t\t\t\tLire la suite\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t20 April 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-14671 post type-post status-publish format-standard has-post-thumbnail hentry category-activites category-culture-et-langues category-vie-associative\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2026\/04\/12\/sejours-culture-et-langue-en-angleterre\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"203\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/01\/Union-Jack-1-300x203.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/01\/Union-Jack-1-300x203.jpg 300w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/01\/Union-Jack-1.jpg 541w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Activit\u00e9s<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.unionjumelages.com\/index.php\/2026\/04\/12\/sejours-culture-et-langue-en-angleterre\/\" >\n\t\t\t\tS\u00e9jours Culture et langue en Angleterre\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Apprendre l&#8217;anglais autrement <\/p>\n\t\t<\/div>\n\t\t\t\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2026\/04\/12\/sejours-culture-et-langue-en-angleterre\/\" >\n\t\t\t\tLire la suite\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t12 April 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-17481 post type-post status-publish format-standard has-post-thumbnail hentry category-vie-associative\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2026\/02\/13\/souvenirs-des-saveurs-du-languedoc\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2026\/03\/7797212977500229001-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2026\/03\/7797212977500229001-300x225.jpg 300w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2026\/03\/7797212977500229001.jpg 320w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Vie associative<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.unionjumelages.com\/index.php\/2026\/02\/13\/souvenirs-des-saveurs-du-languedoc\/\" >\n\t\t\t\tSouvenirs des &#8220;Saveurs du Languedoc&#8221;\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Une semaine gastronomique et culturelle \u00e0 Narbonne-Plage<\/p>\n\t\t<\/div>\n\t\t\t\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2026\/02\/13\/souvenirs-des-saveurs-du-languedoc\/\" >\n\t\t\t\tLire la suite\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t13 February 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-16124 post type-post status-publish format-standard has-post-thumbnail hentry category-vie-associative\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2026\/01\/12\/fetes-des-associations-a-vierzon-et-bourges\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/10\/bourges-4-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/10\/bourges-4-300x225.jpg 300w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/10\/bourges-4-1024x768.jpg 1024w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/10\/bourges-4-768x576.jpg 768w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/10\/bourges-4-1536x1152.jpg 1536w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/10\/bourges-4-2048x1536.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Vie associative<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.unionjumelages.com\/index.php\/2026\/01\/12\/fetes-des-associations-a-vierzon-et-bourges\/\" >\n\t\t\t\tF\u00eates des associations \u00e0 Vierzon et Bourges\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Belle initiative  l&#8217;association de jumelage de Bourges !<\/p>\n\t\t<\/div>\n\t\t\t\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2026\/01\/12\/fetes-des-associations-a-vierzon-et-bourges\/\" >\n\t\t\t\tLire la suite\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t12 January 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-16264 post type-post status-publish format-standard has-post-thumbnail hentry category-vie-associative\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2026\/01\/03\/rencontre-a-evian\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"255\" height=\"155\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/11\/Screenshot-2025-11-03-at-14-55-54-Evian-Banque-dimages-et-photos-libres-de-droit-iStock.png\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Vie associative<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.unionjumelages.com\/index.php\/2026\/01\/03\/rencontre-a-evian\/\" >\n\t\t\t\tRencontre \u00e0 Evian\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p> Entre Lac et Montagnes Du 27 juin au 4 juillet  2026<\/p>\n\t\t<\/div>\n\t\t\t\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2026\/01\/03\/rencontre-a-evian\/\" >\n\t\t\t\tLire la suite\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t3 January 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-16439 post type-post status-publish format-standard has-post-thumbnail hentry category-vie-associative\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/10\/08\/echos-du-congres-deurojumelages-a-alvor-portimao\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"218\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/12\/Screenshot-2025-12-08-at-10-49-06-CR-de-lAG-Alvor.pdf-300x218.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/12\/Screenshot-2025-12-08-at-10-49-06-CR-de-lAG-Alvor.pdf-300x218.png 300w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/12\/Screenshot-2025-12-08-at-10-49-06-CR-de-lAG-Alvor.pdf.png 334w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Vie associative<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/10\/08\/echos-du-congres-deurojumelages-a-alvor-portimao\/\" >\n\t\t\t\tEchos du congr\u00e8s d&#8217;Eurojumelages \u00e0 Alvor (Portimao)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Organis\u00e9 du 9 au 12 novembre 2025<\/p>\n\t\t<\/div>\n\t\t\t\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/10\/08\/echos-du-congres-deurojumelages-a-alvor-portimao\/\" >\n\t\t\t\tLire la suite\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t8 October 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-15909 post type-post status-publish format-standard has-post-thumbnail hentry category-vie-associative\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/10\/01\/rencontre-a-nancy-2025\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"144\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/10\/temp_file_1754830148351-3-300x144.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/10\/temp_file_1754830148351-3-300x144.jpg 300w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/10\/temp_file_1754830148351-3-1024x490.jpg 1024w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/10\/temp_file_1754830148351-3-768x368.jpg 768w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/10\/temp_file_1754830148351-3.jpg 1536w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Vie associative<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/10\/01\/rencontre-a-nancy-2025\/\" >\n\t\t\t\tRencontre franco-allemande \u00e0 Nancy 2025\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Organis\u00e9e par  Paris-Poste, Bourges et Ch\u00e2lons en champagne   du 9 au 13 juillet 2025<\/p>\n\t\t<\/div>\n\t\t\t\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/10\/01\/rencontre-a-nancy-2025\/\" >\n\t\t\t\tLire la suite\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t1 October 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-16212 post type-post status-publish format-standard has-post-thumbnail hentry category-vie-associative\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/09\/24\/souvenirs-de-saint-etienne-2025\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/10\/Cret-de-lOeillon-groupe-2-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/10\/Cret-de-lOeillon-groupe-2-225x300.jpg 225w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/10\/Cret-de-lOeillon-groupe-2.jpg 600w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Vie associative<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/09\/24\/souvenirs-de-saint-etienne-2025\/\" >\n\t\t\t\tSouvenirs de Saint-Etienne 2025\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Organis\u00e9 par l&#8217;UNJPT du 26 au 28 septembre 2025<\/p>\n\t\t<\/div>\n\t\t\t\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/09\/24\/souvenirs-de-saint-etienne-2025\/\" >\n\t\t\t\tLire la suite\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t24 September 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-15868 post type-post status-publish format-standard has-post-thumbnail hentry category-vie-associative\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/09\/08\/rencontre-lyon-kielce-a-st-malo-2025\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"138\" height=\"300\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/09\/photo-Lyon-St-malo-1-138x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/09\/photo-Lyon-St-malo-1-138x300.jpg 138w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/09\/photo-Lyon-St-malo-1.jpg 354w\" sizes=\"(max-width: 138px) 100vw, 138px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Vie associative<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/09\/08\/rencontre-lyon-kielce-a-st-malo-2025\/\" >\n\t\t\t\tRencontre Lyon Kielce 2025 en Bretagne\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Rencontre franco-polonaise organis\u00e9e par  Lyon  du 27\/06 au 05\/07\/2025<\/p>\n\t\t<\/div>\n\t\t\t\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/09\/08\/rencontre-lyon-kielce-a-st-malo-2025\/\" >\n\t\t\t\tLire la suite\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t8 September 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-15826 post type-post status-publish format-standard has-post-thumbnail hentry category-vie-associative\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/09\/05\/rencontre-au-mont-dore-2026\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"203\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/09\/Screenshot-2025-09-05-at-14-05-24--300x203.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/09\/Screenshot-2025-09-05-at-14-05-24--300x203.png 300w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/09\/Screenshot-2025-09-05-at-14-05-24-.png 654w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Vie associative<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/09\/05\/rencontre-au-mont-dore-2026\/\" >\n\t\t\t\tRencontre au  Mont-Dore 2026\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Organis\u00e9 par &#8220;Strasbourg-Alsace&#8221;  du 6 au 13 juin 2026<\/p>\n\t\t<\/div>\n\t\t\t\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/09\/05\/rencontre-au-mont-dore-2026\/\" >\n\t\t\t\tLire la suite\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t5 September 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-15723 post type-post status-publish format-standard has-post-thumbnail hentry category-activites category-vie-associative\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/08\/21\/sejour-montagne-dans-les-dolomites-2026\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/02\/Pozza-2025-2-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/02\/Pozza-2025-2-300x169.jpg 300w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/02\/Pozza-2025-2-1024x576.jpg 1024w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/02\/Pozza-2025-2-768x432.jpg 768w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/02\/Pozza-2025-2-1536x864.jpg 1536w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/02\/Pozza-2025-2.jpg 1684w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Activit\u00e9s<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/08\/21\/sejour-montagne-dans-les-dolomites-2026\/\" >\n\t\t\t\tS\u00e9jour montagne dans les Dolomites 2026\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Organis\u00e9 par &#8220;Strasbourg-Alsace&#8221;  \u00e0 Pozza Di Fassa du 18 au 25 janvier 2026<\/p>\n\t\t<\/div>\n\t\t\t\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/08\/21\/sejour-montagne-dans-les-dolomites-2026\/\" >\n\t\t\t\tLire la suite\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t21 August 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-15253 post type-post status-publish format-standard has-post-thumbnail hentry category-vie-associative\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/08\/20\/cours-de-francais-sur-la-cote-dopale\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/07\/cours-francais-2025-groupe-300x225.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/07\/cours-francais-2025-groupe-300x225.jpeg 300w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/07\/cours-francais-2025-groupe.jpeg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Vie associative<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/08\/20\/cours-de-francais-sur-la-cote-dopale\/\" >\n\t\t\t\tCours de fran\u00e7ais  sur la C\u00f4te d\u2019Opale\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Organis\u00e9 sur la C\u00f4te d\u2019Opale par l&#8217;association de Lille<\/p>\n\t\t<\/div>\n\t\t\t\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/08\/20\/cours-de-francais-sur-la-cote-dopale\/\" >\n\t\t\t\tLire la suite\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t20 August 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-15105 post type-post status-publish format-standard has-post-thumbnail hentry category-vie-associative\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/07\/27\/post-ag-paris-2025\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/07\/post-ag-2025-passage-entete-300x225.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/07\/post-ag-2025-passage-entete-300x225.jpeg 300w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/07\/post-ag-2025-passage-entete.jpeg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Vie associative<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/07\/27\/post-ag-paris-2025\/\" >\n\t\t\t\tPost AG Paris 2025\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Demandez le programme !<\/p>\n\t\t<\/div>\n\t\t\t\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/07\/27\/post-ag-paris-2025\/\" >\n\t\t\t\tLire la suite\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t27 July 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-15014 post type-post status-publish format-standard has-post-thumbnail hentry category-vie-associative\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/07\/16\/la-baie-de-somme-la-cote-picarde\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"236\" height=\"300\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/06\/groupe-baie-somme-2025-236x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/06\/groupe-baie-somme-2025-236x300.jpg 236w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/06\/groupe-baie-somme-2025.jpg 738w\" sizes=\"(max-width: 236px) 100vw, 236px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Vie associative<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/07\/16\/la-baie-de-somme-la-cote-picarde\/\" >\n\t\t\t\tLa Baie de Somme  &#8211; La C\u00f4te Picarde\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p> Petit s\u00e9jour fort agr\u00e9able dans les Hauts de France pour profiter des jolis paysages<br \/>\nde la baie de  Somme.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/07\/16\/la-baie-de-somme-la-cote-picarde\/\" >\n\t\t\t\tLire la suite\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t16 July 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-15691 post type-post status-publish format-standard has-post-thumbnail hentry category-vie-associative\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/06\/11\/randonnee-en-bretagne\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/08\/1751556439487-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/08\/1751556439487-300x225.jpg 300w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/08\/1751556439487-1024x769.jpg 1024w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/08\/1751556439487-768x577.jpg 768w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/08\/1751556439487-1536x1153.jpg 1536w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/08\/1751556439487-2048x1538.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Vie associative<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/06\/11\/randonnee-en-bretagne\/\" >\n\t\t\t\tRandonn\u00e9e en Bretagne\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Randonn\u00e9e organis\u00e9e par Strasbourg-Alsace<br \/>\ndu 28 juin au 5 juillet 2025<\/p>\n\t\t<\/div>\n\t\t\t\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/06\/11\/randonnee-en-bretagne\/\" >\n\t\t\t\tLire la suite\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t11 June 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-14821 post type-post status-publish format-standard has-post-thumbnail hentry category-vie-associative\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/06\/05\/le-mot-de-la-nouvelle-presidente\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"259\" height=\"300\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/06\/sylvie-association-bis-259x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/06\/sylvie-association-bis-259x300.jpg 259w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/06\/sylvie-association-bis.jpg 367w\" sizes=\"(max-width: 259px) 100vw, 259px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Vie associative<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/06\/05\/le-mot-de-la-nouvelle-presidente\/\" >\n\t\t\t\tLe mot de la nouvelle Pr\u00e9sidente\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>AG 2025 : Rel\u00e8ve, p\u00e9rennit\u00e9 assur\u00e9e<\/p>\n\t\t<\/div>\n\t\t\t\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/06\/05\/le-mot-de-la-nouvelle-presidente\/\" >\n\t\t\t\tLire la suite\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t5 June 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-14791 post type-post status-publish format-standard has-post-thumbnail hentry category-activites category-vie-associative\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/05\/27\/tossa-de-mar-2025\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/05\/IMG_6707-002-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/05\/IMG_6707-002-300x225.jpg 300w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/05\/IMG_6707-002-1024x768.jpg 1024w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/05\/IMG_6707-002-768x576.jpg 768w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/05\/IMG_6707-002-1536x1152.jpg 1536w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/05\/IMG_6707-002-2048x1536.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Activit\u00e9s<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/05\/27\/tossa-de-mar-2025\/\" >\n\t\t\t\tTossa de Mar 2025\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Souvenirs du cours d&#8217;espagnol de Tossa de Mar, organis\u00e9 par l&#8217;association de G\u00e9rone<\/p>\n\t\t<\/div>\n\t\t\t\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/05\/27\/tossa-de-mar-2025\/\" >\n\t\t\t\tLire la suite\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t27 May 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-14854 post type-post status-publish format-standard has-post-thumbnail hentry category-activites category-vie-associative tag-jumelage-ag\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/05\/23\/souvenirs-de-lag-2025\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"135\" src=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/06\/Fiap-AG-Paris-25-300x135.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/06\/Fiap-AG-Paris-25-300x135.jpg 300w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/06\/Fiap-AG-Paris-25-1024x459.jpg 1024w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/06\/Fiap-AG-Paris-25-768x345.jpg 768w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/06\/Fiap-AG-Paris-25-1536x689.jpg 1536w, https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2025\/06\/Fiap-AG-Paris-25-2048x919.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Activit\u00e9s<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/05\/23\/souvenirs-de-lag-2025\/\" >\n\t\t\t\tSouvenirs de l&#8217;AG 2025\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Souvenirs de l&#8217; AG \u00e0 Paris &#8211;  Mai 2025<\/p>\n\t\t<\/div>\n\t\t\t\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.unionjumelages.com\/index.php\/2025\/05\/23\/souvenirs-de-lag-2025\/\" >\n\t\t\t\tLire la suite\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t23 May 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Vie associative<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-300","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vie associative - Union Jumelages<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unionjumelages.com\/index.php\/vie-associative\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vie associative - Union Jumelages\" \/>\n<meta property=\"og:description\" content=\"Vie associative\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unionjumelages.com\/index.php\/vie-associative\/\" \/>\n<meta property=\"og:site_name\" content=\"Union Jumelages\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-30T19:15:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.unionjumelages.com\/index.php\/vie-associative\/\",\"url\":\"https:\/\/www.unionjumelages.com\/index.php\/vie-associative\/\",\"name\":\"Vie associative - Union Jumelages\",\"isPartOf\":{\"@id\":\"https:\/\/www.unionjumelages.com\/#website\"},\"datePublished\":\"2021-03-17T09:13:08+00:00\",\"dateModified\":\"2022-06-30T19:15:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.unionjumelages.com\/index.php\/vie-associative\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.unionjumelages.com\/index.php\/vie-associative\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.unionjumelages.com\/index.php\/vie-associative\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.unionjumelages.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vie associative\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.unionjumelages.com\/#website\",\"url\":\"https:\/\/www.unionjumelages.com\/\",\"name\":\"Union Jumelages\",\"description\":\"Un site utilisant WordPress\",\"publisher\":{\"@id\":\"https:\/\/www.unionjumelages.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.unionjumelages.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.unionjumelages.com\/#organization\",\"name\":\"Union Jumelages\",\"url\":\"https:\/\/www.unionjumelages.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.unionjumelages.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2021\/03\/cropped-union-jumelages.jpg\",\"contentUrl\":\"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2021\/03\/cropped-union-jumelages.jpg\",\"width\":113,\"height\":95,\"caption\":\"Union Jumelages\"},\"image\":{\"@id\":\"https:\/\/www.unionjumelages.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vie associative - Union Jumelages","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unionjumelages.com\/index.php\/vie-associative\/","og_locale":"en_US","og_type":"article","og_title":"Vie associative - Union Jumelages","og_description":"Vie associative","og_url":"https:\/\/www.unionjumelages.com\/index.php\/vie-associative\/","og_site_name":"Union Jumelages","article_modified_time":"2022-06-30T19:15:24+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.unionjumelages.com\/index.php\/vie-associative\/","url":"https:\/\/www.unionjumelages.com\/index.php\/vie-associative\/","name":"Vie associative - Union Jumelages","isPartOf":{"@id":"https:\/\/www.unionjumelages.com\/#website"},"datePublished":"2021-03-17T09:13:08+00:00","dateModified":"2022-06-30T19:15:24+00:00","breadcrumb":{"@id":"https:\/\/www.unionjumelages.com\/index.php\/vie-associative\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unionjumelages.com\/index.php\/vie-associative\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.unionjumelages.com\/index.php\/vie-associative\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.unionjumelages.com\/"},{"@type":"ListItem","position":2,"name":"Vie associative"}]},{"@type":"WebSite","@id":"https:\/\/www.unionjumelages.com\/#website","url":"https:\/\/www.unionjumelages.com\/","name":"Union Jumelages","description":"Un site utilisant WordPress","publisher":{"@id":"https:\/\/www.unionjumelages.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unionjumelages.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.unionjumelages.com\/#organization","name":"Union Jumelages","url":"https:\/\/www.unionjumelages.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.unionjumelages.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2021\/03\/cropped-union-jumelages.jpg","contentUrl":"https:\/\/www.unionjumelages.com\/wp-content\/uploads\/2021\/03\/cropped-union-jumelages.jpg","width":113,"height":95,"caption":"Union Jumelages"},"image":{"@id":"https:\/\/www.unionjumelages.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.unionjumelages.com\/index.php\/wp-json\/wp\/v2\/pages\/300"}],"collection":[{"href":"https:\/\/www.unionjumelages.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.unionjumelages.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.unionjumelages.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unionjumelages.com\/index.php\/wp-json\/wp\/v2\/comments?post=300"}],"version-history":[{"count":49,"href":"https:\/\/www.unionjumelages.com\/index.php\/wp-json\/wp\/v2\/pages\/300\/revisions"}],"predecessor-version":[{"id":6438,"href":"https:\/\/www.unionjumelages.com\/index.php\/wp-json\/wp\/v2\/pages\/300\/revisions\/6438"}],"wp:attachment":[{"href":"https:\/\/www.unionjumelages.com\/index.php\/wp-json\/wp\/v2\/media?parent=300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}